{"id":850,"count":0,"description":"","link":"https:\/\/www.cetm.es\/en\/tag\/consejo-de-ministros-en\/","name":"Consejo de Ministros","slug":"consejo-de-ministros-en","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.cetm.es\/en\/tag\/consejo-de-ministros-en\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cetm.es\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/850\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.cetm.es\\\/en\\\/#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.cetm.es\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.cetm.es\\\/en\\\/tag\\\/consejo-de-ministros-en\\\/#listItem\",\"name\":\"Consejo de Ministros\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.cetm.es\\\/en\\\/tag\\\/consejo-de-ministros-en\\\/#listItem\",\"position\":2,\"name\":\"Consejo de Ministros\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.cetm.es\\\/en\\\/#listItem\",\"name\":\"Inicio\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.cetm.es\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/850\\\/#collectionpage\",\"url\":\"https:\\\/\\\/www.cetm.es\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/850\\\/\",\"name\":\"Consejo de Ministros | Confederaci\\u00f3n Espa\\u00f1ola de Transporte de Mercanc\\u00edas\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cetm.es\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cetm.es\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/850\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cetm.es\\\/en\\\/#organization\",\"name\":\"Confederaci\\u00f3n Espa\\u00f1ola de Transporte de Mercanc\\u00edas\",\"description\":\"\\ud83d\\ude9a Entra en la web de la CETM, la organizaci\\u00f3n que agrupa a m\\u00e1s de 31.000 empresas de transporte. Noticias \\u2713  Servicios Sintra \\u2713  Formaci\\u00f3n \\u2713 SolRed \\u2713\",\"url\":\"https:\\\/\\\/www.cetm.es\\\/en\\\/\",\"telephone\":\"+34917444700\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cetmtransporte\\\/\",\"https:\\\/\\\/twitter.com\\\/CetmTransporte\",\"https:\\\/\\\/www.instagram.com\\\/cetmtransporte\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCmZfXVohbtHg4brTslQtqyQ\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/cetm-confederaci-n-espa-ola-de-transporte-de-mercanc-as\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cetm.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.cetm.es\\\/en\\\/\",\"name\":\"Confederaci\\u00f3n Espa\\u00f1ola de Transporte de Mercanc\\u00edas\",\"description\":\"\\ud83d\\ude9a Entra en la web de la CETM, la organizaci\\u00f3n que agrupa a m\\u00e1s de 31.000 empresas de transporte. Noticias \\u2713  Servicios Sintra \\u2713  Formaci\\u00f3n \\u2713 SolRed \\u2713\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cetm.es\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Consejo de Ministros | Confederaci\u00f3n Espa\u00f1ola de Transporte de Mercanc\u00edas","description":"","canonical_url":"https:\/\/www.cetm.es\/en\/tag\/consejo-de-ministros-en\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.cetm.es\/en\/wp-json\/wp\/v2\/tags\/850\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.cetm.es\/en\/#listItem","position":1,"name":"Inicio","item":"https:\/\/www.cetm.es\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.cetm.es\/en\/tag\/consejo-de-ministros-en\/#listItem","name":"Consejo de Ministros"}},{"@type":"ListItem","@id":"https:\/\/www.cetm.es\/en\/tag\/consejo-de-ministros-en\/#listItem","position":2,"name":"Consejo de Ministros","previousItem":{"@type":"ListItem","@id":"https:\/\/www.cetm.es\/en\/#listItem","name":"Inicio"}}]},{"@type":"CollectionPage","@id":"https:\/\/www.cetm.es\/en\/wp-json\/wp\/v2\/tags\/850\/#collectionpage","url":"https:\/\/www.cetm.es\/en\/wp-json\/wp\/v2\/tags\/850\/","name":"Consejo de Ministros | Confederaci\u00f3n Espa\u00f1ola de Transporte de Mercanc\u00edas","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.cetm.es\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.cetm.es\/en\/wp-json\/wp\/v2\/tags\/850\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/www.cetm.es\/en\/#organization","name":"Confederaci\u00f3n Espa\u00f1ola de Transporte de Mercanc\u00edas","description":"\ud83d\ude9a Entra en la web de la CETM, la organizaci\u00f3n que agrupa a m\u00e1s de 31.000 empresas de transporte. Noticias \u2713  Servicios Sintra \u2713  Formaci\u00f3n \u2713 SolRed \u2713","url":"https:\/\/www.cetm.es\/en\/","telephone":"+34917444700","sameAs":["https:\/\/www.facebook.com\/cetmtransporte\/","https:\/\/twitter.com\/CetmTransporte","https:\/\/www.instagram.com\/cetmtransporte\/","https:\/\/www.youtube.com\/channel\/UCmZfXVohbtHg4brTslQtqyQ","https:\/\/www.linkedin.com\/company\/cetm-confederaci-n-espa-ola-de-transporte-de-mercanc-as"]},{"@type":"WebSite","@id":"https:\/\/www.cetm.es\/en\/#website","url":"https:\/\/www.cetm.es\/en\/","name":"Confederaci\u00f3n Espa\u00f1ola de Transporte de Mercanc\u00edas","description":"\ud83d\ude9a Entra en la web de la CETM, la organizaci\u00f3n que agrupa a m\u00e1s de 31.000 empresas de transporte. Noticias \u2713  Servicios Sintra \u2713  Formaci\u00f3n \u2713 SolRed \u2713","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.cetm.es\/en\/#organization"}}]}},"_links":{"self":[{"href":"https:\/\/www.cetm.es\/en\/wp-json\/wp\/v2\/tags\/850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cetm.es\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.cetm.es\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.cetm.es\/en\/wp-json\/wp\/v2\/posts?tags=850"},{"href":"https:\/\/www.cetm.es\/en\/wp-json\/wp\/v2\/tribe_events?tags=850"},{"href":"https:\/\/www.cetm.es\/en\/wp-json\/wp\/v2\/tec_calendar_embed?tags=850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}